{"id":2337,"date":"2018-12-11T19:19:14","date_gmt":"2018-12-11T17:19:14","guid":{"rendered":"http:\/\/bardina.blog.pangea.org\/?p=2337"},"modified":"2018-12-11T19:19:14","modified_gmt":"2018-12-11T17:19:14","slug":"10-articles-mes-del-xiri-acte-a-premia-de-mar-la-meva-anima-i-jo-de-dolors-marin-xirinacs-com-a-referent-articles-de-jorge-molinari","status":"publish","type":"post","link":"https:\/\/bardina.blog.pangea.org\/es\/2018\/12\/11\/10-articles-mes-del-xiri-acte-a-premia-de-mar-la-meva-anima-i-jo-de-dolors-marin-xirinacs-com-a-referent-articles-de-jorge-molinari\/","title":{"rendered":"10 art\u00edculos m\u00e1s del Xiri. Acto en Premi\u00e0 de Mar. \u00abMi alma y yo\u00bb de Dolors Mar\u00edn. Xirinacs como referente. Art\u00edculos de Jorge Molinari."},"content":{"rendered":"<p><span style=\"color: #330000\"><b>Sumario:<\/b><br \/>\n1. Presentaci\u00f3n.<br \/>\n2. Web Bardina: 10 art\u00edculos m\u00e1s del Xiri de la secci\u00f3n \u00abDiario de un senador\u00bb. 232 en total.<br \/>\n3. Blog Xirinacs: Acto de \u00d2mnium Premi\u00e0 de Mar. 13-12-2018.<br \/>\n4. Web Bardina: \u00abMi alma y yo\u00bb, de Dolors Mar\u00edn Tuy\u00e0.<br \/>\n5. Web Bardina: \u00abXirinacs como referente\u00bb, de Xavi Aguilar por \u00abEl Punt Avui+\u00bb.<br \/>\n6. Blog \u00abAbordando eso gris, que parece la teor\u00eda\u00bb: \u00abExplicar: un desaf\u00edo\u00bb y \u00abLa econom\u00eda en la Venezuela actual\u00bb, de Jorge Aniceto Molinari.<\/span><\/p>\n<p><b>1. Presentaci\u00f3n.<\/b><\/p>\n<p>&nbsp;<\/p>\n<div align=\"justify\">\n<p><span style=\"color: #330000\">En este env\u00edo del Centro de Estudios Joan Bardina compartimos con vosotros 10 art\u00edculos m\u00e1s escritos por Llu\u00eds Maria Xirinacs de los publicados en el desaparecido rotativo \u00ab<i>Mundo Diario<\/i>\u00bb entre el 2 y el 21 de Mayo del a\u00f1o 1978. Es remarcable como en muchos de los art\u00edculos de su secci\u00f3n \u00ab<i>Diario de un senador<\/i>\u00bb se mantienen claras similitudes entre la situaci\u00f3n de aquel tiempo y la situaci\u00f3n actual.<\/span><\/p>\n<p><span style=\"color: #330000\">A continuaci\u00f3n os anunciamos un acontecimiento para el jueves 13 de Diciembre de este a\u00f1o en Premi\u00e0 de Mar, en el cual participar\u00e1n miembros de la Fundaci\u00f3n Randa-Llu\u00eds M. Xirinacs y se emitir\u00e1 un documental relacionado con el mismo Xirinacs.<\/span><\/p>\n<p><span style=\"color: #330000\">La psic\u00f3loga Dolors Mar\u00edn nos proporciona su \u00faltimo art\u00edculo publicado en el rotativo \u00ab<i>Pened\u00e8s Econ\u00f2mic<\/i>\u00bb. Como en otros art\u00edculos suyos anteriores, Dolors Mar\u00edn aprovecha el conocimiento del modelo filos\u00f3fico del conocimiento de la realidad, \u00ab<i>Globalium<\/i>\u00bb, dise\u00f1ado por Llu\u00eds Maria Xirinacs.<\/span><\/p>\n<p><span style=\"color: #330000\">Compartimos con vosotros un art\u00edculo publicado en su d\u00eda a \u00ab<i>El Punt Avui+<\/i>\u00bb que nos informa de ciertos detalles de la lucha pacifista de Xirinacs, y como esta queda reflejada en las luchas pacifistas actuales.<\/span><\/p>\n<p><span style=\"color: #330000\">Finalmente, nuestro colaborador en la Uruguay, Jorge Aniceto Molinari, nos proporciona dos art\u00edculos donde analiza las necesidades de la econom\u00eda actual tomando como muestra la situaci\u00f3n de las econom\u00edas de Latinoam\u00e9rica.<\/span><\/p>\n<p><span style=\"color: #330000\">En el primer art\u00edculo responde a una cr\u00edtica que le han hecho llegar a prop\u00f3sito de las leyes econ\u00f3micas. C\u00f3mo dice otro colaborador nuestro, Jordi Griera, una cr\u00edtica es en cierto modo un regalo. En el segundo art\u00edculo, Jorge Molinari comenta un art\u00edculo de opini\u00f3n sobre la situaci\u00f3n inflacionaria en Venezuela.<\/span><\/p>\n<p><span style=\"color: #330000\">Molinari reivindica, una vez m\u00e1s, la necesidad de establecer un patr\u00f3n monetario \u00fanico que finalice con la especulaci\u00f3n entre divisas, haciendo que la moneda sea exclusivamente telem\u00e1tica para acabar con la evasi\u00f3n fiscal, lo cual permitir\u00eda que con un impuesto sobre cada compraventa se puedan alcanzar las necesidades del sector p\u00fablico tales como la educaci\u00f3n, la sanidad, las pensiones, los servicios e infraestructuras p\u00fablicas.<\/span><\/p>\n<p><span style=\"color: #330000\">Muchas gracias por compartir esta informaci\u00f3n.<\/span><\/p>\n<\/div>\n<p><span style=\"color: #330000\">\u00a0<\/span><\/p>\n<div align=\"right\"><span style=\"color: #330000\">Equipo del Centro de Estudios Joan Bardina.<\/span><br \/>\n<span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/nw2\/index-es.htm\">http:\/\/www.bardina.org\/nw2\/index-es.htm<\/a><\/span><\/div>\n<p><span style=\"color: #330000\"><br \/>\n<b>2. Web Bardina: 10 art\u00edculos m\u00e1s del Xiri de la secci\u00f3n \u00abDiario de un senador\u00bb. 232 en total.<\/b><\/span><\/p>\n<p>&nbsp;<\/p>\n<div align=\"justify\">\n<p><span style=\"color: #330000\">Os informamos que hemos introducido, dentro del sitio web del Centro de Estudios Joan Bardina, 10 art\u00edculos m\u00e1s de Llu\u00eds Maria Xirinacs, escritos cuando \u00e9l era senador independiente en las Cortes Constituyentes espa\u00f1olas de los a\u00f1os 1977 hasta 1979, de los publicados en el rotativo \u00ab<i>Mundo Diario<\/i>\u00bb, dentro de su secci\u00f3n \u00ab<i>Diario de un senador<\/i>\u00bb.<\/span><\/p>\n<p><span style=\"color: #330000\">Con estos 10 art\u00edculos ya son 232 los recuperados en castellano dentro de esta secci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #330000\">El enlace del \u00edndice donde se puede acceder a todos los art\u00edculos ya recuperados es el siguiente:<\/span><\/p>\n<p><span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/diario-senador\/diario-senador-indice-es.htm\">http:\/\/www.bardina.org\/diario-senador\/diario-senador-indice-es.htm<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">Los enlaces de los diferentes art\u00edculos recientemente recuperados son, por orden cronol\u00f3gico del m\u00e1s antiguo al m\u00e1s moderno:<\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Hay parados productivos<\/i>\u00bb. Martes, 2 de Mayo de 1978.<\/span><br \/>\n<span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-02-hay-parados-productivos-es.htm\">http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-02-hay-parados-productivos-es.htm<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Secuestro con retraso<\/i>\u00bb. Mi\u00e9rcoles, 3 de Mayo de 1978.<\/span><br \/>\n<span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-03-secuestro-con-retraso-es.htm\">http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-03-secuestro-con-retraso-es.htm<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Ferrol<\/i>\u00bb. S\u00e1bado, 6 de Mayo de 1978.<\/span><br \/>\n<span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-06-ferrol-es.htm\">http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-06-ferrol-es.htm<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Luchas populares gallegas<\/i>\u00bb. Domingo, 7 de Mayo de 1978.<\/span><br \/>\n<span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-07-luchas-populares-gallegas-es.htm\">http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-07-luchas-populares-gallegas-es.htm<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Cr\u00f3nica gallega<\/i>\u00bb. Martes, 9 de Mayo de 1978.<\/span><br \/>\n<span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-09-cronica-gallega-es.htm\">http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-09-cronica-gallega-es.htm<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Rizando el rizo<\/i>\u00bb. Mi\u00e9rcoles, 10 de Mayo de 1978.<\/span><br \/>\n<span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-10-rizando-el-rizo-es.htm\">http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-10-rizando-el-rizo-es.htm<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Fiscal fiscalizado<\/i>\u00bb. Jueves, 11 de Mayo de 1978.<\/span><br \/>\n<span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-11-fiscal-fiscalizado-es.htm\">http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-11-fiscal-fiscalizado-es.htm<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Un nuevo Finisterre<\/i>\u00bb. Domingo, 14 de Mayo de 1978.<\/span><br \/>\n<span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-14-un-nuevo-finisterre-es.htm\">http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-14-un-nuevo-finisterre-es.htm<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Navarros cat\u00f3licos<\/i>\u00bb. Mi\u00e9rcoles, 17 de Mayo de 1978.<\/span><br \/>\n<span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-17-navarros-catolicos-es.htm\">http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-17-navarros-catolicos-es.htm<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Defensa civil de un pueblo<\/i>\u00bb. Domingo, 21 de Mayo de 1978.<\/span><br \/>\n<span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-21-defensa-civil-de-un-pueblo-es.htm\">http:\/\/www.bardina.org\/diario-senador\/diario-senador-1978-05-21-defensa-civil-de-un-pueblo-es.htm<\/a><\/span><\/p>\n<\/div>\n<p><span style=\"color: #330000\"><br \/>\n<b>3. Blog Xirinacs: Acto de \u00d2mnium Premi\u00e0 de Mar. 13-12-2018.<\/b><\/span><\/p>\n<p>&nbsp;<\/p>\n<div align=\"justify\">\n<p><span style=\"color: #330000\">Hemos publicado la entrada del blog Xirinacs donde se anuncia el acto del pr\u00f3ximo jueves 13 de Diciembre del 2018 en Premi\u00e0 de Mar, donde est\u00e1 prevista la emisi\u00f3n de un documental sobre Xirinacs y la asistencia de los miembros de la Fundaci\u00f3n Randa-Llu\u00eds M. Xirinacs \u00c0ngels Bald\u00f3 y N\u00faria Roig.<\/span><\/p>\n<p><span style=\"color: #330000\">Jueves, 13 de diciembre a las 19h30\u2019.<\/span><\/p>\n<p><span style=\"color: #330000\">Lugar:<\/span><\/p>\n<p><span style=\"color: #330000\">Centro C\u00edvico de Premi\u00e0 de Mar.<\/span><br \/>\n<span style=\"color: #330000\">Calle Esperan\u00e7a, 19.<\/span><\/p>\n<p><span style=\"color: #330000\">El enlace de la nueva entrada en catal\u00e1n es el siguiente:<\/span><\/p>\n<p><span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.xirinacs.org\/wp\/2018\/12\/08\/acte-domnium-premia-de-mar\/\">http:\/\/www.xirinacs.org\/wp\/2018\/12\/08\/acte-domnium-premia-de-mar\/<\/a><\/span><\/p>\n<\/div>\n<p><span style=\"color: #330000\"><br \/>\n<b>4. Web Bardina: \u00abMi alma y yo\u00bb, de Dolors Mar\u00edn Tuy\u00e0.<\/b><\/span><\/p>\n<p>&nbsp;<\/p>\n<div align=\"justify\">\n<p><span style=\"color: #330000\">Hemos reproducido el art\u00edculo titulado \u00ab<i>Mi alma y yo<\/i>\u00bb, firmado por Dolors Mar\u00edn Tuy\u00e0 y publicado al rotativo \u00ab<i>Pened\u00e8s Econ\u00f2mic<\/i>\u00bb, el Noviembre del 2018, en su p\u00e1gina 18.<\/span><\/p>\n<p><span style=\"color: #330000\">Mi alma y yo.<\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Mi alma no soy yo. Yo soy yo. Yo tengo mi alma. Mi alma es la que lo sabe todo de m\u00ed, de mi propia vida interior de afectos, ideas, emociones, sensaciones y decisiones. Lo sabe todo mejor que yo porque no se distrae como yo. Yo me distraigo en el ruido y el trasiego diario. Tener una mentalidad anal\u00edtica y emp\u00edrica hace que las densas nieblas formales me alejen de mi propia alma. Entonces es cuando me desanimo. Para recuperar el estado de \u00e1nimo hay que saber escuchar y atender el alma (&#8230;)<\/i>\u00bb.<\/span><\/p>\n<p><span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/nw\/escrits\/dolors-marin-tuya-mi-alma-y-yo-es.htm\">http:\/\/www.bardina.org\/nw\/escrits\/dolors-marin-tuya-mi-alma-y-yo-es.htm<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">Agradecemos a la psic\u00f3loga y miembro de la Fundaci\u00f3n Randa-Llu\u00eds M. Xirinacs, Dolors Mar\u00edn Tuy\u00e0, su contribuci\u00f3n con la aportaci\u00f3n de este art\u00edculo, haciendo servir su conocimiento del \u00ab<i>Glob\u00e0lium<\/i>\u00bb de Llu\u00eds Maria Xirinacs.<\/span><\/p>\n<\/div>\n<p><span style=\"color: #330000\"><br \/>\n<b>5. Web Bardina: \u00abXirinacs como referente\u00bb, de Xavi Aguilar por \u00abEl Punt Avui+\u00bb.<\/b><\/span><\/p>\n<p>&nbsp;<\/p>\n<div align=\"justify\">\n<p><span style=\"color: #330000\">Hemos reproducido el art\u00edculo titulado \u00ab<i>Xirinacs como referente<\/i>\u00bb, firmado por Xavi Aguilar y publicado al rotativo \u00ab<i>El Punt Avui+<\/i>\u00bb, el 25 de Noviembre del 2018, en su p\u00e1gina 4.<\/span><\/p>\n<p><span style=\"color: #330000\">Xirinacs como referente.<\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Por el extremo riesgo que comporta y la gran firmeza y convicci\u00f3n moral que requiere, la huelga de hambre es una v\u00eda de protesta muy poco frecuente, pero no ajena a las reclamaciones del catalanismo, y todav\u00eda menos a la de los l\u00edderes pol\u00edticos pacifistas en general. El inicio, ayer, de la huelga de hambre de Jordi S\u00e0nchez y Jordi Turull tuvo lugar el mismo d\u00eda en que, 45 a\u00f1os atr\u00e1s, el pol\u00edtico, sacerdote y fil\u00f3sofo Llu\u00eds Maria Xirinacs tambi\u00e9n inici\u00f3 una. Corr\u00eda, por lo tanto, el 1973 y el activista estaba en r\u00e9gimen de prisi\u00f3n preventiva en la Modelo, acusado de difusi\u00f3n de propaganda ilegal y en espera de ser juzgado por el r\u00e9gimen franquista. Su acci\u00f3n reclamaba la amnist\u00eda de los presos pol\u00edticos y especialmente la libertad de los 113 detenidos durante una reuni\u00f3n de la Asamblea de Catalu\u00f1a en la iglesia Santa Maria Mitjancera de Barcelona, entre los cuales se contaba (&#8230;)<\/i>\u00bb.<\/span><\/p>\n<p><span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/www.bardina.org\/nw\/escrits\/el-punt-avui-xavi-aguilar-xirinacs-como-referente-es.htm\">http:\/\/www.bardina.org\/nw\/escrits\/el-punt-avui-xavi-aguilar-xirinacs-como-referente-es.htm<\/a><\/span><\/p>\n<\/div>\n<p><span style=\"color: #330000\"><br \/>\n<b>6. Blog \u00abAbordando eso gris, que parece la teor\u00eda\u00bb: \u00abExplicar: un desaf\u00edo\u00bb y \u00abLa econom\u00eda en la Venezuela actual\u00bb, de Jorge Aniceto Molinari.<\/b><\/span><\/p>\n<p>&nbsp;<\/p>\n<div align=\"justify\">\n<p><span style=\"color: #330000\">Hemos introducido en el blog \u00ab<i>Abordando eso gris, que parece la teor\u00eda<\/i>\u00bb, los art\u00edculos titulados \u00ab<i>Explicar: un desaf\u00edo<\/i>\u00bb y \u00ab<i>La econom\u00eda en la Venezuela actual<\/i>\u00bb.<\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Explicar: un desaf\u00edo<\/i>\u00bb. Viernes, 30 de Noviembre de 2018.<\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Muy buen desaf\u00edo. No es com\u00fan por lo general que los amigos digan claramente lo que piensan y en este caso tiene un doble valor. La sinceridad y adem\u00e1s un desaf\u00edo para explicar m\u00e1s claramente lo que pienso que siempre tiene la dificultad de no saber uno si la recepci\u00f3n de la idea es correcta, es o no completa (&#8230;)<\/i>\u00bb.<\/span><\/p>\n<p><span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/eso-gris.blog.pangea.org\/2018\/11\/30\/explicar-un-desafio\/\">http:\/\/eso-gris.blog.pangea.org\/2018\/11\/30\/explicar-un-desafio\/<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>La econom\u00eda en la Venezuela actual<\/i>\u00bb. Jueves, 6 de Diciembre de 2018.<\/span><\/p>\n<p><span style=\"color: #330000\">\u00ab<i>Reproducimos una nota de Pascualina Curcio y luego la comentamos: (&#8230;)<\/i>\u00bb.<\/span><\/p>\n<p><span style=\"color: #330000\"><a class=\"moz-txt-link-freetext\" href=\"http:\/\/eso-gris.blog.pangea.org\/2018\/12\/06\/la-economia-en-la-venezuela-actual\/\">http:\/\/eso-gris.blog.pangea.org\/2018\/12\/06\/la-economia-en-la-venezuela-actual\/<\/a><\/span><\/p>\n<p><span style=\"color: #330000\">Agradecemos la colaboraci\u00f3n de Jorge Aniceto Molinari al proporcionarnos estos art\u00edculos.<\/span><\/p>\n<p><span style=\"color: #330000\">Muchas gracias por compartir esta informaci\u00f3n.<\/span><\/p>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Sumario: 1. Presentaci\u00f3n. 2. Web Bardina: 10 art\u00edculos m\u00e1s del Xiri de la secci\u00f3n \u00abDiario de un senador\u00bb. 232 en total. 3. Blog Xirinacs: Acto de \u00d2mnium Premi\u00e0 de Mar. 13-12-2018. 4. Web Bardina: \u00abMi alma y yo\u00bb, de Dolors &hellip; <a href=\"https:\/\/bardina.blog.pangea.org\/es\/2018\/12\/11\/10-articles-mes-del-xiri-acte-a-premia-de-mar-la-meva-anima-i-jo-de-dolors-marin-xirinacs-com-a-referent-articles-de-jorge-molinari\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1870,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[53486,39124,39246,18478,118019,18479,118008,118009,18426,118018,18452,18434,57601,39202,39125,39130,118021,118017,18115,39154,39245,118020,18986],"tags":[],"class_list":["post-2337","post","type-post","status-publish","format-standard","hentry","category-angels-baldo-bullido","category-dolors-marin-tuya","category-evasio-fiscal","category-fundacio-randa-lluis-m-xirinacs","category-galicia","category-jordi-griera","category-jordi-sanchez-picanyol","category-jordi-turull-negre","category-jorge-aniceto-molinari","category-llatinoamerica","category-lluis-maria-xirinacs","category-medicina","category-moneda","category-navarra","category-nuria-roig-esteve","category-omnium-cultural","category-pascualina-curcio-curcio","category-premia-de-mar","category-presentacions-presentaciones","category-uruguai","category-venecuela","category-xavier-aguilar","category-xerrades-debats-charlas-debates"],"views":363,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts\/2337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/users\/1870"}],"replies":[{"embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/comments?post=2337"}],"version-history":[{"count":1,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts\/2337\/revisions"}],"predecessor-version":[{"id":2338,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts\/2337\/revisions\/2338"}],"wp:attachment":[{"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/media?parent=2337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/categories?post=2337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/tags?post=2337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}