{"id":42,"date":"2009-10-21T17:18:03","date_gmt":"2009-10-21T15:18:03","guid":{"rendered":"http:\/\/bardina.blog.pangea.org\/?p=42"},"modified":"2014-01-22T15:46:34","modified_gmt":"2014-01-22T13:46:34","slug":"interpretando-los-escritos-de-agusti-chalaux-de-subira","status":"publish","type":"post","link":"https:\/\/bardina.blog.pangea.org\/es\/2009\/10\/21\/interpretando-los-escritos-de-agusti-chalaux-de-subira\/","title":{"rendered":"Interpretando los escritos de Agust\u00ed Chalaux de Subir\u00e0"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify\">Sin duda el aporte intelectual y las lecciones de \u00e9tica social dejadas por este connotado pensador catal\u00e1n <!--more-->son muy significativas e importantes, pero la lectura y comprensi\u00f3n de los escritos de Agust\u00ed no son nada sencillas, y no porque este activista social se haya expresado en forma oscura, sino porque los temas que aborda son sumamente complejos.<\/p>\n<p style=\"text-align: justify\">No vale hacer una lectura ligera y superficial de los documentos legados por Agust\u00ed porque ello sirve de poco. Para realmente poder solucionar los problemas hay que comprender los mecanismos del capitalismo hasta en sus aristas m\u00e1s \u00edntimas, y entonces y solamente entonces podremos esbozar y alg\u00fan d\u00eda alcanzar un capitalismo comunitario, un capitalismo social.<\/p>\n<p style=\"text-align: right\">Publicado por Juan Carlos Anselmi.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Sin duda el aporte intelectual y las lecciones de \u00e9tica social dejadas por este connotado pensador catal\u00e1n<\/p>\n","protected":false},"author":106,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[18111,17903],"tags":[],"class_list":["post-42","post","type-post","status-publish","format-standard","hentry","category-juan-carlos-anselmi","category-textos-en-castellano"],"views":287,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":4,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts\/42\/revisions"}],"predecessor-version":[{"id":2087,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts\/42\/revisions\/2087"}],"wp:attachment":[{"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/media?parent=42"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/categories?post=42"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/es\/wp-json\/wp\/v2\/tags?post=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}