{"id":1962,"date":"2013-11-12T02:06:41","date_gmt":"2013-11-12T00:06:41","guid":{"rendered":"http:\/\/bardina.blog.pangea.org\/?p=1962"},"modified":"2017-05-11T10:25:44","modified_gmt":"2017-05-11T08:25:44","slug":"desmuntant-els-paranys-del-diner","status":"publish","type":"post","link":"https:\/\/bardina.blog.pangea.org\/it\/2013\/11\/12\/desmuntant-els-paranys-del-diner\/","title":{"rendered":"Come smontare le trappole del denaro."},"content":{"rendered":"<p><\/p>\n<p align=\"center\"><strong>Come smontare le trappole del denaro.<\/strong><\/p>\n<p align=\"justify\"><a href=\"http:\/\/bardina.blog.pangea.org\/files\/2013\/11\/Corrupcio_diner_anonim.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-2032\" alt=\"Corrupcio_diner_anonim\" src=\"http:\/\/bardina.blog.pangea.org\/files\/2013\/11\/Corrupcio_diner_anonim.jpg\" width=\"263\" height=\"191\" \/><\/a>Per cominciare, condividiamo pienamente la preoccupazione espressa da diverse persone e gruppi attorno alla possibilit\u00e0 che l\u2019introduzione di un denaro esclusivamente telematico diventi<!--more--> il tranello di una tirannia telematica, sotto il controllo di una minoranza che non risponda delle sue azioni davanti a nessuno.<\/p>\n<p align=\"justify\">Questa preoccupazione nasce dalla possibilit\u00e0 che la rete telematica venga sottomessa al controllo esclusivo della elite economica e politica imperante. Il controllo, o piuttosto la mancanza di controllo, irresponsabile della rete o delle reti, \u00e8 quello che ci conduce verso la gran trappola che ci preoccupa, e non il denaro elettronico in se stesso. E questa insidia \u00e8 gi\u00e0 presente attualmente senza aspettare che il denaro elettronico diventi esclusivo.<\/p>\n<p align=\"justify\">Il denaro anonimo, dapprima sotto forma di monete, e poi di monete e biglietti, fu creato 4300 anni fa sotto il regno di Sargon I re di Akkad, e la sua apparizione coincide con l\u2019inizio degli imperialismi moderni successivi che persistono ancora ai nostri giorni. Questo denaro anonimo, dicevamo, \u00e8 lo strumento che rese possibili fatti come l\u2019attentato contro John Fitzgerald Kennedy il 22 novembre 1963, il colpo di stato dell\u201911 settembre 1973 in Cile contro Salvador Allende, o l\u2019attentato contro Olof Palme il 28 febbraio 1986 in Svezia, quando questi dirigenti si dedicavano, o avevano il progetto di portare a termine delle azioni governative o di denuncia a favore dei loro popoli rispettivi.<\/p>\n<div align=\"center\">\n<table width=\"67%\" border=\"0\">\n<tbody>\n<tr>\n<td height=\"150\"><a href=\"http:\/\/bardina.blog.pangea.org\/files\/2013\/11\/John_Fitzgerald_Kennedy_117x150.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1963\" alt=\"John Fitzgerald Kennedy.\" src=\"http:\/\/bardina.blog.pangea.org\/files\/2013\/11\/John_Fitzgerald_Kennedy_117x150.jpg\" width=\"117\" height=\"150\" \/><\/a><\/td>\n<td height=\"150\"><a href=\"http:\/\/bardina.blog.pangea.org\/files\/2013\/11\/Salvador_Allende_Gossens_136x150.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1965\" alt=\"Salvador Allende Gossens.\" src=\"http:\/\/bardina.blog.pangea.org\/files\/2013\/11\/Salvador_Allende_Gossens_136x150.jpg\" width=\"136\" height=\"150\" \/><\/a><\/td>\n<td height=\"150\"><a href=\"http:\/\/bardina.blog.pangea.org\/files\/2013\/11\/Olof_Palme_210x150.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1964\" alt=\"Olof Palme.\" src=\"http:\/\/bardina.blog.pangea.org\/files\/2013\/11\/Olof_Palme_210x150.jpg\" width=\"210\" height=\"150\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p align=\"center\"><strong>Da sinistra a destra: John F. Kennedy, Salvador Allende Gossens e Olof Palme. Fonte: Wikipedia.<\/strong><\/p>\n<\/div>\n<p align=\"justify\">Noi del Centre d\u2019Estudis Joan Bardina, per evitare la prevedibile tirannia telematica che comporterebbe un denaro telematico sotto il controllo dispotico della plutocrazia o dei governi, rivendichiamo diverse misure, fra queste che le reti telematiche che gestiscono il denaro elettronico si assoggettino al controllo esclusivo di una giustizia indipendente dai poteri esecutivi e legislativi delle diverse amministrazioni. Una giustizia pure indipendente dai poteri privati, per mezzo dell\u2019assegnazione alla stessa di una percentuale fissa dei budget, sia ordinari che straordinari, di ogni stato, gestita questa percentuale dalla giustizia stessa.<\/p>\n<p align=\"justify\">Come esempio contrario ci troviamo che nello stato spagnolo le diverse amministrazioni esecutive dei diversi partiti hanno sottomesso la giusticia alla pi\u00f9 assoluta indigenza di risorse di ogni specie, per cui i giudici e i tribunali si trovano in balia delle pressioni dei pi\u00f9 forti in ogni processo, persino dell\u2019autorit\u00e0 politica stessa. I giudici e i tribunali si trovano sotto la minaccia della corruzione e delle pressioni, pagato tutto quanto merc\u00e8 l\u2019uso di un denaro anonimo che non lascia nessuna traccia giuridica di ogni scambio, oppure di un denaro elettronico entro una rete monetaria telematica sotto controllo privato, dove per\u00f2 chi gestisce questo controllo privato pu\u00f2 alterarne arbitrariamente il contenuto ed eliminare ogni tipo di prove.<\/p>\n<p align=\"justify\">Un Sistema Generale come noi lo rivendichiamo deve comportare diverse misure che agevolino l\u2019eliminazione non solo della corruzione ma anche della miseria materiale, perche con un denaro esclusivamente nominativo e telematico la carit\u00e0 diviene praticamente irrealizzabile e si devono garantire delle entrate minime per tutte quelle persone che non abbiano un salario o una pensione. In concreto stiamo parlando di un reddito basico universale.<\/p>\n<p align=\"justify\">Bisogna ricordare che soffriamo una crisi di sovrapproduzione. C\u2019\u00e8 abbondanza di prodotti, gente disposta a comprarli, ma non c\u2019e del denaro sul mercato che permetta il loro acquisto. L\u2019automazione sempre crescente, la meccanizzazione e la robotizzazione dei sistemi di produzione dei beni basici ci portano verso una societ\u00e0 dove una minoranza d\u2019imprenditori dispone della maggioranza dei mezzi di produzione, ma dove si accumulano degli stock che non si possono vendere per il fatto che il resto della gente si trova nell\u2019indigenza a causa della disoccupazione.<\/p>\n<p align=\"justify\">Un denaro telematico nominativo esclusivo deve ammettere che l\u2019autorit\u00e0 politica abbia la capacit\u00e0 di inventare e disinventare il denaro necessario per mantenere l\u2019equilibrio fra l\u2019offerta e la domanda, ed evitare cos\u00ec che ogni volta che si inventi del denaro questo si faccia attraverso un indebitamento che cresce in modo esponenziale, come succede negli USA con la Riserva Federale, e nella zona euro con la Banca Centrale Europea. Quest\u2019inebitamento \u00e8 la causa presente della rovina di un gran numero di stati e di privati, e questo produce la chiusura dei servizi pubblici mantenuti dalle diverse amministrazioni. Mentre che col denaro anonimo era impossibile per chiunque avere una conoscenza esatta del mercato, con il denaro exclusivamente telematico l\u2019autorit\u00e0 politica disporr\u00e0, per la prima volta da 4300 anni, di dati statistici affidabili dell\u2019insieme del mercato, essendo questa una condizione previa necessaria per una adeguata pianificazione.<\/p>\n<p align=\"justify\">Un denaro telematico esclusivamente nominativo deve comportare pure il passaggio da uno stato di fatto, sottomesso ai poteri di fatto, ad un vero stato di diritto, dove ogni operazione commerciale lasci dietro di s\u00e9 una prova giuridica, condizione necessaria per l\u2019esercizio della responsabilit\u00e0, ma dove i dati particolari di ogni persona si trovino a disposizione della persona stessa, e nelle mani di un giudice o di un tribunale soltanto nel caso in cui venga iniziato un processo in rapporto con questa persona. Nello stesso modo, una giustizia dotata delle risorse e del personale sufficienti pu\u00f2 occuparsi pi\u00f9 rapidamente dei processi, garantendo sempre le dovute garanzie processuali e risolvendo senza eternizzarli i diversi conflitti giuridici che si producono nella societ\u00e0.<\/p>\n<p align=\"justify\">Con un denaro elettronico senza le garanzie menzionate, ed altre che si possono vedere nei documenti della nostra web (<a href=\"http:\/\/bardina.org\/mtemit07.htm\">http:\/\/bardina.org\/mtemit07.htm<\/a>), \u00e8 pi\u00f9 facile che si producano i tranelli che abbiamo menzionato.<\/p>\n<p align=\"justify\">Ma cos\u00ec come ci preoccupa questa possibile trappola del denaro elettronico, \u00e8 pure deplorevole la situazione attuale, in cui ci troviamo sottomessi all\u2019inganno del denaro anonimo, dove qualunque proposito di cambiamento politico a favore dell\u2019insieme della citadinanza fallisce per il fatto che i poteri di fatto dispongono di abbondante denaro anonimo con il quale pagheranno le pressioni, la corruzione ed i delitti impuni, impedendo ripetutamente la necessaria evoluzione politica, economica e sociale dell\u2019umanit\u00e0.<\/p>\n<p align=\"justify\">Molto probabilmente, allo stesso modo che l\u2019invenzione del denaro provoc\u00f2 l\u2019inizio degli imperialismi moderni, che si protraggono da 4300 anni fino ai giorni nostri, un denaro telematico esclusivamente nominativo, ma con le dovute imprescindibili garanzie, puo essere l\u2019origine di una nuova era di pace, giustizia e responsabilit\u00e0 in tutti gli ambiti dell\u2019attivit\u00e0 umana.<\/p>\n<p align=\"justify\">Grazie di far seguire questa informazione.<\/p>\n<p align=\"right\">Brauli Tamarit Tamarit.<\/p>\n<p align=\"right\">Lunedi, 11 novembre 2013.<\/p>\n<p align=\"right\">Traduzione: Loto Perrella.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ci spiace, ma questo articolo \u00e8 disponibile soltanto in Catal\u00e0.<\/p>\n","protected":false},"author":106,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[18446,18477,270,19732,269,19426,19731,211,17903,17620,22709,244,19733],"tags":[],"class_list":["post-1962","post","type-post","status-publish","format-standard","hentry","category-brauli-tamarit","category-centre-destudis-joan-bardina","category-economia","category-john-fitzgerald-kennedy","category-moneda-telematica","category-olof-palme","category-salvador-allende-gossens","category-texts-in-english","category-textos-en-castellano","category-texts-en-catala","category-texts-en-esperanto","category-textes-en-francais","category-texts-en-italia"],"views":1083,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/bardina.blog.pangea.org\/it\/wp-json\/wp\/v2\/posts\/1962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bardina.blog.pangea.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bardina.blog.pangea.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/it\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/it\/wp-json\/wp\/v2\/comments?post=1962"}],"version-history":[{"count":19,"href":"https:\/\/bardina.blog.pangea.org\/it\/wp-json\/wp\/v2\/posts\/1962\/revisions"}],"predecessor-version":[{"id":2154,"href":"https:\/\/bardina.blog.pangea.org\/it\/wp-json\/wp\/v2\/posts\/1962\/revisions\/2154"}],"wp:attachment":[{"href":"https:\/\/bardina.blog.pangea.org\/it\/wp-json\/wp\/v2\/media?parent=1962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/it\/wp-json\/wp\/v2\/categories?post=1962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bardina.blog.pangea.org\/it\/wp-json\/wp\/v2\/tags?post=1962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}